{"id":39231,"date":"2026-08-11T19:49:41","date_gmt":"2026-08-11T17:49:41","guid":{"rendered":"https:\/\/hofmann-global.com\/?p=39231"},"modified":"2026-08-12T10:02:22","modified_gmt":"2026-08-12T08:02:22","slug":"pulsar-gana-el-premio-red-dot-award-2026-por-la-experiencia-de-usuario-de-su-interfaz","status":"publish","type":"post","link":"https:\/\/hofmann-global.com\/es\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/","title":{"rendered":"Pulsar gana el Red Dot Award 2026 de Interfaz y Experiencia de Usuario"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Nos complace mucho anunciar que nuestro nuevo software de medici\u00f3n Pulsar ha sido galardonado con el Red Dot Award 2026 en la categor\u00eda de Interfaz y Experiencia de Usuario. El galard\u00f3n reconoce nuestro desarrollo de software m\u00e1s reciente y marca un hito importante para el proyecto Pulsar. Para nosotros, este reconocimiento confirma el compromiso de combinar tecnolog\u00eda de medici\u00f3n de alto rendimiento con una experiencia de usuario moderna e intuitiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Excelente por su dise\u00f1o sobresaliente<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El premio Red Dot es uno de los galardones reconocidos internacionalmente por su dise\u00f1o sobresaliente y se concede en diversos \u00e1mbitos como el dise\u00f1o de productos, de marcas y de comunicaci\u00f3n. Se premian los productos y soluciones que convencen, entre otras cosas, por su forma, funcionalidad, innovaci\u00f3n y su dise\u00f1o integral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de la candidatura, presentamos Pulsar en un v\u00eddeo propio, mostrando el desarrollo de la plataforma, la apariencia visual y el dise\u00f1o de la interfaz de usuario. El foco principal se centr\u00f3 en la interacci\u00f3n de los distintos elementos y en c\u00f3mo estos contribuyen a una experiencia de usuario coherente y orientada al usuario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un nuevo est\u00e1ndar para el software de medici\u00f3n Hofmann<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este galard\u00f3n, ahora podemos llevar el sello Red Dot Winner de Interfaz y Experiencia de Usuario. Para nuestros clientes y socios, el reconocimiento es una caracter\u00edstica de calidad adicional y confirma que el dise\u00f1o y la facilidad de uso de Pulsar cumplen con un est\u00e1ndar internacionalmente reconocido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Pulsar hemos invertido mucho tiempo y conocimientos t\u00e9cnicos en el desarrollo de un sistema de medici\u00f3n que combina precisi\u00f3n, funcionalidad y facilidad de uso. El resultado es una plataforma de software que hace que el acceso a la tecnolog\u00eda de equilibrado moderna sea m\u00e1s intuitivo y, al mismo tiempo, ofrece el rendimiento que los usuarios esperan de las soluciones de Hofmann. Por lo tanto, el Red Dot Award no es solo un reconocimiento especial para nosotros, sino tambi\u00e9n una motivaci\u00f3n para seguir desarrollando soluciones innovadoras para la tecnolog\u00eda de equilibrado en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede encontrar m\u00e1s informaci\u00f3n sobre el Red Dot Award y los productos galardonados en el sitio web oficial del Red Dot Award:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.red-dot.org\/\" data-type=\"link\" data-id=\"https:\/\/www.red-dot.org\/\">Premio Red Dot<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Agradecemos a todos los que participaron en el desarrollo de Pulsar por su dedicaci\u00f3n y compromiso. Este premio es un reconocimiento a todo el equipo detr\u00e1s de la nueva generaci\u00f3n del software de medici\u00f3n Hofmann.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>El nuevo software de medici\u00f3n Pulsar de Hofmann recibe el galardonado internacionalmente Red Dot Award de Interfaz y Experiencia de Usuario por su dise\u00f1o sobresaliente.<\/p>","protected":false},"author":3,"featured_media":39230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience - Hofmann Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hofmann-global.com\/es\/pulsar-gana-el-premio-red-dot-award-2026-por-la-experiencia-de-usuario-de-su-interfaz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience - Hofmann Global\" \/>\n<meta property=\"og:description\" content=\"Die neue Hofmann Mess-Software Pulsar erh\u00e4lt den international anerkannten Red Dot Award f\u00fcr Interface &amp; User Experience f\u00fcr herausragendes Design.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hofmann-global.com\/es\/pulsar-gana-el-premio-red-dot-award-2026-por-la-experiencia-de-usuario-de-su-interfaz\/\" \/>\n<meta property=\"og:site_name\" content=\"Hofmann Global\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-11T17:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T08:02:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hofmann-global.com\/wp-content\/uploads\/Reddot.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/\"},\"author\":{\"name\":\"cs\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#\\\/schema\\\/person\\\/39d13fe3885b6d168d7f0f08b80fdf07\"},\"headline\":\"Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience\",\"datePublished\":\"2026-08-11T17:49:41+00:00\",\"dateModified\":\"2026-08-12T08:02:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/\"},\"wordCount\":364,\"publisher\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hofmann-global.com\\\/wp-content\\\/uploads\\\/Reddot.png\",\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/\",\"url\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/\",\"name\":\"Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience - Hofmann Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hofmann-global.com\\\/wp-content\\\/uploads\\\/Reddot.png\",\"datePublished\":\"2026-08-11T17:49:41+00:00\",\"dateModified\":\"2026-08-12T08:02:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hofmann-global.com\\\/wp-content\\\/uploads\\\/Reddot.png\",\"contentUrl\":\"https:\\\/\\\/hofmann-global.com\\\/wp-content\\\/uploads\\\/Reddot.png\",\"width\":940,\"height\":788,\"caption\":\"red dot award\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hofmann-global.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#website\",\"url\":\"https:\\\/\\\/hofmann-global.com\\\/\",\"name\":\"Hofmann Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#organization\"},\"alternateName\":\"Hofmann Mess- und Auswuchttechnik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hofmann-global.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#organization\",\"name\":\"Hofmann Global\",\"alternateName\":\"Hofmann Mess- und Auswuchttechnik\",\"url\":\"https:\\\/\\\/hofmann-global.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hofmann-global.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hofmann_Logo_500px.png\",\"contentUrl\":\"https:\\\/\\\/hofmann-global.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Hofmann_Logo_500px.png\",\"width\":500,\"height\":83,\"caption\":\"Hofmann Global\"},\"image\":{\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4KxqFL_pHyMNYDAPCUizPg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hofmann-global\",\"https:\\\/\\\/www.instagram.com\\\/hofmann.global\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hofmann-global.com\\\/#\\\/schema\\\/person\\\/39d13fe3885b6d168d7f0f08b80fdf07\",\"name\":\"cs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc8262c551206d9457005a8fd02fab626dcbaef5d43d94582d04057fef291a4d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc8262c551206d9457005a8fd02fab626dcbaef5d43d94582d04057fef291a4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc8262c551206d9457005a8fd02fab626dcbaef5d43d94582d04057fef291a4d?s=96&d=mm&r=g\",\"caption\":\"cs\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pulsar gana el premio Red Dot Award 2026 de interfaz y experiencia de usuario - Hofmann Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hofmann-global.com\/es\/pulsar-gana-el-premio-red-dot-award-2026-por-la-experiencia-de-usuario-de-su-interfaz\/","og_locale":"es_ES","og_type":"article","og_title":"Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience - Hofmann Global","og_description":"Die neue Hofmann Mess-Software Pulsar erh\u00e4lt den international anerkannten Red Dot Award f\u00fcr Interface & User Experience f\u00fcr herausragendes Design.","og_url":"https:\/\/hofmann-global.com\/es\/pulsar-gana-el-premio-red-dot-award-2026-por-la-experiencia-de-usuario-de-su-interfaz\/","og_site_name":"Hofmann Global","article_published_time":"2026-08-11T17:49:41+00:00","article_modified_time":"2026-08-12T08:02:22+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/hofmann-global.com\/wp-content\/uploads\/Reddot.png","type":"image\/png"}],"author":"cs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cs","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/#article","isPartOf":{"@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/"},"author":{"name":"cs","@id":"https:\/\/hofmann-global.com\/#\/schema\/person\/39d13fe3885b6d168d7f0f08b80fdf07"},"headline":"Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience","datePublished":"2026-08-11T17:49:41+00:00","dateModified":"2026-08-12T08:02:22+00:00","mainEntityOfPage":{"@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/"},"wordCount":364,"publisher":{"@id":"https:\/\/hofmann-global.com\/#organization"},"image":{"@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/#primaryimage"},"thumbnailUrl":"https:\/\/hofmann-global.com\/wp-content\/uploads\/Reddot.png","articleSection":["Allgemein"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/","url":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/","name":"Pulsar gana el premio Red Dot Award 2026 de interfaz y experiencia de usuario - Hofmann Global","isPartOf":{"@id":"https:\/\/hofmann-global.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/#primaryimage"},"image":{"@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/#primaryimage"},"thumbnailUrl":"https:\/\/hofmann-global.com\/wp-content\/uploads\/Reddot.png","datePublished":"2026-08-11T17:49:41+00:00","dateModified":"2026-08-12T08:02:22+00:00","breadcrumb":{"@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/#primaryimage","url":"https:\/\/hofmann-global.com\/wp-content\/uploads\/Reddot.png","contentUrl":"https:\/\/hofmann-global.com\/wp-content\/uploads\/Reddot.png","width":940,"height":788,"caption":"red dot award"},{"@type":"BreadcrumbList","@id":"https:\/\/hofmann-global.com\/pulsar-gewinnt-red-dot-award-2026-fuer-interface-user-experience\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hofmann-global.com\/"},{"@type":"ListItem","position":2,"name":"Pulsar gewinnt Red Dot Award 2026 f\u00fcr Interface &amp; User Experience"}]},{"@type":"WebSite","@id":"https:\/\/hofmann-global.com\/#website","url":"https:\/\/hofmann-global.com\/","name":"Hofmann Global","description":"","publisher":{"@id":"https:\/\/hofmann-global.com\/#organization"},"alternateName":"Hofmann Mess- und Auswuchttechnik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hofmann-global.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hofmann-global.com\/#organization","name":"Hofmann Global","alternateName":"Hofmann Mess- und Auswuchttechnik","url":"https:\/\/hofmann-global.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hofmann-global.com\/#\/schema\/logo\/image\/","url":"https:\/\/hofmann-global.com\/wp-content\/uploads\/2025\/05\/Hofmann_Logo_500px.png","contentUrl":"https:\/\/hofmann-global.com\/wp-content\/uploads\/2025\/05\/Hofmann_Logo_500px.png","width":500,"height":83,"caption":"Hofmann Global"},"image":{"@id":"https:\/\/hofmann-global.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UC4KxqFL_pHyMNYDAPCUizPg","https:\/\/www.linkedin.com\/company\/hofmann-global","https:\/\/www.instagram.com\/hofmann.global\/"]},{"@type":"Person","@id":"https:\/\/hofmann-global.com\/#\/schema\/person\/39d13fe3885b6d168d7f0f08b80fdf07","name":"cs","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dc8262c551206d9457005a8fd02fab626dcbaef5d43d94582d04057fef291a4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc8262c551206d9457005a8fd02fab626dcbaef5d43d94582d04057fef291a4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc8262c551206d9457005a8fd02fab626dcbaef5d43d94582d04057fef291a4d?s=96&d=mm&r=g","caption":"cs"}}]}},"_links":{"self":[{"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/posts\/39231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/comments?post=39231"}],"version-history":[{"count":4,"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/posts\/39231\/revisions"}],"predecessor-version":[{"id":39248,"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/posts\/39231\/revisions\/39248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/media\/39230"}],"wp:attachment":[{"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/media?parent=39231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/categories?post=39231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hofmann-global.com\/es\/wp-json\/wp\/v2\/tags?post=39231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}